{"id":87176,"date":"2013-06-07T23:38:07","date_gmt":"2013-06-07T19:38:07","guid":{"rendered":"https:\/\/mospat.ru\/?p=87176"},"modified":"2014-06-22T02:22:33","modified_gmt":"2014-06-21T22:22:33","slug":"zavershilsya-vizit-svyatejjshego-patriarkha-moskovskogo-i-vseya-rusi-kirilla-v-ehlladskuyu-pravoslavnuyu-cerkov","status":"publish","type":"post","link":"https:\/\/old.mospat.ru\/it\/2013\/06\/07\/news87176\/","title":{"rendered":"Conclusa la visita del Patriarca Kirill in Grecia"},"content":{"rendered":"<p>Dall\u2019 1 al 7 giugno 2013, su invito di Sua Beatitudine l&#8217;Arcivescovo di Atene e di tutta la Grecia Ieronymos e del Santo Sinodo della Chiesa ortodossa ellenica, Sua santit\u00e0 il Patriarca di Mosca e di tutta la Rus\u2019 Kirill ha visitato la Grecia.<\/p>\n<p>Durante la visita, Sua Santit\u00e0 \u00e8 stato accompagnato dal presidente del Dipartimento per le relazioni ecclesiastiche esterne del Patriarcato di Mosca, metropolita Hilarion di Volokolamsk, dal responsabile della Segreteria amministrativa del Patriarcato di Mosca, vescovo Sergij di Solnechnogorsk, dal presidente del Dipartimento sinodale per l\u2019informazione V.R. Legojda, dal vicepresidente del Dipartimento per le relazioni esterne, arciprete Nikolaj Balashov, dal segretario per le relazioni interortodosse dello stesso Dipartimento, arciprete Igor Yakymchuk, dall\u2019assistente del presidente del Diaprtimento \u00a0arcidiacono Vladimir Nazarkin, dal capo della segreteria personale di Sua Santit\u00e0 il Patriarca M.G. Kuksov.<\/p>\n<p>Hanno inoltre accompagnato Sua Santit\u00e0: il capo del Servizio di protocollo, arciprete Andrej Milkin, il capo del Servizio stampa del Patriarca di Mosca e di tutta la Rus\u2019, diacono Aleksandr Volkov, il responsabile ad interim del Servizio Comunicazione del Dipartimento per le relazioni ecclesiastiche esterne, sacerdote Ilija Kosyh, il membro dello staff del del Dipartimento per le relazioni esterne, A. Churyakov.<\/p>\n<p>All&#8217;aeroporto di Atene Sua Santit\u00e0 il Patriarca ha incontrato Sua Beatitudine l&#8217;Arcivescovo Ieronymos; i Primati della Chiesa russa e della Chiesa ellenica si sono diretti verso la chiesa del Santo Martire Dionigi l&#8217;Areopagita a Kolonaki. Nella chiesa gremita di fedeli, Sua Santit\u00e0 il Patriarca Kirill ha tenuto un servizio di preghiera.<\/p>\n<p>In serata, nel palazzo arcivescovile ad Atene si \u00e8 svolto un incontro tra i Primati delle due Chiese.<\/p>\n<p>Il 2 giugno, nella quinta domenica dopo Pasqua, dedicata alla Samaritana, Sua Santit\u00e0 il Patriarca di Mosca e di tutta la Rus\u2019 Kirill e Sua Beatitudine l&#8217;Arcivescovo di Atene e di tutta la Grecia Ieronymos hanno celebrato la Divina Liturgia nel tempio ateniese del Grande Martire e Guaritore San Panteleimon in Akharnon.<\/p>\n<p>Lo stesso giorno, il Santo Sinodo della Chiesa ortodossa ellenica ha dato un ricevimento in onore degli ospiti.<\/p>\n<p>Poi il Patriarca Kirill e Sua Beatitudine l&#8217;Arcivescovo Ieronymos hanno visitato la chiesa russa della Santissima Trinit\u00e0 ad Atene e la chiesa cattedrale in costruzione in onore della Madre di Dio \u00abPanagh\u00eca Sumela\u00bb in Akharnon, nella zona a nord di Atene. Sua Santit\u00e0 ha donato alla comunit\u00e0 di lingua russa della chiesa parte delle reliquie di San Serafino di Sarov.<\/p>\n<p>Il secondo giorno, si \u00e8 tenuta la visita al centro caritativo dell&#8217;Arcidiocesi di Atene \u00abMissione\u00bb.<\/p>\n<p>Il 3 giugno, Sua Santit\u00e0 il Patriarca ha visitato la residenza del Santo Sinodo della Chiesa ortodossa ellenica e ha condotto un servizio di preghiera presso il monastero Petraki. Ha poi preso parte ad una seduta solenne del Santo Sinodo della Chiesa ellenica e ha rivolto un discorso ai partecipanti. Nel corso della riunione, Sua Santit\u00e0 \u00e8 stato insignito del massimo riconoscimento della Chiesa ortodossa ellenica, la Gran Croce dell&#8217;apostolo Paolo. Alti premi sono stati assegnati anche ai membri della delegazione della Chiesa ortodossa russa.<\/p>\n<p>Poi Sua Santit\u00e0 il Patriarca ha avuto un colloquio con Sua Beatitudine l&#8217;Arcivescovo Ieronymos e con i membri del Santo Sinodo della Chiesa ellenica.<\/p>\n<p>Lo stesso giorno, il Patriarca Kirill ha avuto un incontro con il Presidente greco K. Papoulias e il primo ministro A. Samaras.<\/p>\n<p>Da Atene, Sua Santit\u00e0 \u00e8 andato a Salonicco, dove ha tenuto un servizio di preghiera nella Cattedrale di San Gregorio Palamas e ha visitato l&#8217;arcidiocesi di Tessalonica. In serata, il metropolita di Tessalonica Anthimos ha dato un ricevimento in onore di Sua Santit\u00e0 il Patriarca di Mosca e di tutta la Rus\u2019 Kirill.<\/p>\n<p>Il giorno successivo, dopo aver pregato dinanzi ai santuari della citt\u00e0, il Patriarca Kirill \u00e8 partito per il Monte Athos. Dal molo \u00e8 andato a Karyes &#8211; il centro amministrativo del Monte Athos, dove ha tenuto un servizio di preghiera nella Cattedrale centrale del Monte Athos. Il Primate della Chiesa ortodossa russa ha inoltre tenuto una riunione con i membri della Santa Epistasia del Santo Monte Athos.<\/p>\n<p>Arrivando al monastero russo di San Panteleimon, Sua Santit\u00e0 il Patriarca ha venerato i santuari del monastero, ha visitato gli edifici del monastero restaurato dopo l&#8217;incendio, ha pregato per i monaci defunti. Sua Santit\u00e0 ha anche visitato i luoghi della vita di San Silvano del Monte Athos.<\/p>\n<p>Il 5 giugno, il Patriarca Kirill ha celebrato la Divina Liturgia presso il monastero di San Panteleimon.<\/p>\n<p>Durante il pellegrinaggio al Monte Athos, il Primate della Chiesa ortodossa russa ha visitato la Grande Lavra di Sant\u2019Atanasio dell\u2019Athos, i monasteri di Iviron e del Pantokrator, l\u2019eremo di Sant\u2019Elia, fondato da San Paissij Velichkovski, i monasteri di Zografou, Chilandari, Vatopedi, Ksilurgu, e il monastero di Sant\u2019 Andrea, dove ha ispezionato i lavori di ristrutturazione del vecchio Russikon.<\/p>\n<p>Il 7 giugno \u00e8 stata celebrata la Divina Liturgia nella chiesa della Protezione del monastero di San Panteleimon. Dopo il servizio, Sua Santit\u00e0 il Patriarca ha incontrato i rappresentanti dei media.<\/p>\n<p>Al termine della visita-pellegrinaggio al Monte Athos, Sua Santit\u00e0 ha incoraggiato gli abitanti del monastero di San Panteleimon, e ha tenuto una conversazione con il padre igumeno del monastero, archimandrita Ieremij.<\/p>\n<p>Nella citt\u00e0 di Veria, il Patriarca di Mosca e di tutta la Rus\u2019 Kirill ha benedetto il monumento all\u2019apostolo Paolo.<\/p>\n<p>Il Primate della Chiesa russa ha visitato il monastero della Panaghia Dovre, dove ha benedetto le campane della chiesa di San Luca (Voyno-Yasenetsky), in fase di costruzione. Nel monastero \u00e8 stato dato un ricevimento in onore del Primate della Chiesa russa.<\/p>\n<p>Al termine della visita, Sua Santit\u00e0 ha condiviso con i giornalisti le sue impressioni sulla terra greca.<\/p>\n<p>Dall &#8216;aeroporto di Salonicco, il Patriarca di Mosca e di tutta la Rus\u2019 Kirill e la sua delegazione sono tornati a casa.<\/p>","protected":false},"excerpt":{"rendered":"<p>Dall\u2019 1 al 7 giugno 2013, su invito di Sua Beatitudine l&#8217;Arcivescovo di Atene e di tutta la Grecia Ieronymos e del Santo Sinodo della Chiesa ortodossa ellenica, Sua santit\u00e0 il Patriarca di Mosca e di tutta la Rus\u2019 Kirill ha visitato la Grecia.<\/p>\n","protected":false},"author":7,"featured_media":87210,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16,9,1,11,12],"tags":[],"_links":{"self":[{"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/posts\/87176"}],"collection":[{"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/comments?post=87176"}],"version-history":[{"count":0,"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/posts\/87176\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/media\/87210"}],"wp:attachment":[{"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/media?parent=87176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/categories?post=87176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/tags?post=87176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}