{"id":27883,"date":"2010-10-12T23:58:59","date_gmt":"2010-10-12T19:58:59","guid":{"rendered":"http:\/\/www.mospat.ru\/?p=27883"},"modified":"2010-10-16T20:59:15","modified_gmt":"2010-10-16T16:59:15","slug":"uchastniki-rossijjsko-italyanskogo-simpoziuma-obsudili-nravstvennye-aspekty-bankovskojj-deyatelnosti","status":"publish","type":"post","link":"https:\/\/old.mospat.ru\/it\/2010\/10\/12\/news27883\/","title":{"rendered":"Simposio sugli aspetti etici dell\u2019attivit\u00e0 bancaria"},"content":{"rendered":"<p>\n\t\t<div id='gallery-2' class='gallery galleryid-27883 gallery-columns-3 gallery-size-thumbnail'>\n\t\t<div class='carousel-wrapper'>\n\t\t\t<div id='carousel-2' class='gallery-carousel'>\n\t\t\t\t<a href=\"https:\/\/old.mospat.ru\/wp-content\/uploads\/2010\/10\/dq21.jpg\" id=\"slide_item_200\" class=\"slide fancybox\" rel=\"gallery1\"><img src=\"https:\/\/old.mospat.ru\/wp-content\/uploads\/timthumb.php?src=https:\/\/old.mospat.ru\/wp-content\/uploads\/2010\/10\/dq21.jpg&w=632&h=380&q=95\" width=\"632\" height=\"380\"><\/a><a href=\"https:\/\/old.mospat.ru\/wp-content\/uploads\/2010\/10\/dq1.jpg\" id=\"slide_item_201\" class=\"slide fancybox\" rel=\"gallery1\"><img src=\"https:\/\/old.mospat.ru\/wp-content\/uploads\/timthumb.php?src=https:\/\/old.mospat.ru\/wp-content\/uploads\/2010\/10\/dq1.jpg&w=632&h=380&q=95\" width=\"632\" height=\"380\"><\/a><a href=\"https:\/\/old.mospat.ru\/wp-content\/uploads\/2010\/10\/dq2.jpg\" id=\"slide_item_202\" class=\"slide fancybox\" rel=\"gallery1\"><img src=\"https:\/\/old.mospat.ru\/wp-content\/uploads\/timthumb.php?src=https:\/\/old.mospat.ru\/wp-content\/uploads\/2010\/10\/dq2.jpg&w=632&h=380&q=95\" width=\"632\" height=\"380\"><\/a><a href=\"https:\/\/old.mospat.ru\/wp-content\/uploads\/2010\/10\/dq3.jpg\" id=\"slide_item_203\" class=\"slide fancybox\" rel=\"gallery1\"><img src=\"https:\/\/old.mospat.ru\/wp-content\/uploads\/timthumb.php?src=https:\/\/old.mospat.ru\/wp-content\/uploads\/2010\/10\/dq3.jpg&w=632&h=380&q=95\" width=\"632\" height=\"380\"><\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class='thumbs-wrapper'>\n\t\t\t<div id='thumbs-2' class='gallery-thumbs'>\n\t\t\t\t<a href=\"#slide_item_200\"><img src=\"https:\/\/old.mospat.ru\/wp-content\/uploads\/timthumb.php?src=https:\/\/old.mospat.ru\/wp-content\/uploads\/2010\/10\/dq21.jpg&w=150&h=100&q=95\"><\/a><a href=\"#slide_item_201\"><img src=\"https:\/\/old.mospat.ru\/wp-content\/uploads\/timthumb.php?src=https:\/\/old.mospat.ru\/wp-content\/uploads\/2010\/10\/dq1.jpg&w=150&h=100&q=95\"><\/a><a href=\"#slide_item_202\"><img src=\"https:\/\/old.mospat.ru\/wp-content\/uploads\/timthumb.php?src=https:\/\/old.mospat.ru\/wp-content\/uploads\/2010\/10\/dq2.jpg&w=150&h=100&q=95\"><\/a><a href=\"#slide_item_203\"><img src=\"https:\/\/old.mospat.ru\/wp-content\/uploads\/timthumb.php?src=https:\/\/old.mospat.ru\/wp-content\/uploads\/2010\/10\/dq3.jpg&w=150&h=100&q=95\"><\/a>\n\t\t\t<\/div>\n\t\t\t<a id='prev-2' class='gallery-thumbs-prev' href='#'><i class='icon-angle-circled-left'><\/i><\/a>\n\t\t\t<a id='next-2' class='gallery-thumbs-next' href='#'><i class='icon-angle-circled-right'><\/i><\/a>\n\t\t<\/div>\n\t<\/div><br \/>\nIl 12 ottobre 2010 si \u00e8 svolto a Mosca, nei locali dell\u2019albergo \u201cDanilovskaja\u201d della Chiesa Ortodossa Russa, il simposio \u201cGli aspetti etici dell\u2019attivit\u00e0 bancaria e il ruolo sociale delle banche: le esperienze della Russia e dell\u2019Italia\u201d.<\/p>\n<p>Alla conferenza hanno partecipato l\u2019igumeno Philipp Rjabych, vicepresidente del Dipartimento per le relazioni esterne del Patriarcato di Mosca, il cardinale Paul Poupard, il presidente dell\u2019Associazione delle banche russe G. Tosunjan, il vicepresidente della Vneshekonombank S. Vasilev, il primo segretario del Consiglio di esperti \u201cEconomia e etica\u201d presso il Patriarca di Mosca e tutte le Russie, nonch\u00e9 segretario del Club degli imprenditori ortodossi P. Shashkin, il deputato della Duma della Federazione Russa P. Medvedev, il capo del reparto internazionale del gruppo \u201cUBI banca\u201d D. Trombi, responsabili italiani e russi di organizzazioni finanziarie, chierici ortodossi e cattolici.<\/p>\n<p>Durante il simposio sono stati affrontati temi riguardanti i principi morali dell\u2019attivit\u00e0 imprenditoriale, l\u2019applicazione pratica del codice etico nel lavoro delle banche, sono state analizzate le cause spirituali della crisi economica mondiale e i tentativi di superarla attraverso il cambiamento dei valori di base del mondo della finanza.<\/p>\n<p>Il simposio \u00e8 stato aperto dall\u2019intervento del card. Paul Poupard, ex-presidente del Pontificio consiglio della Cultura. Ha poi parlato il presidente dell\u2019Associazione della banche russe G. Tosunjan. Questi ha sottolineato l\u2019importanza dell\u2019aspetto etico nell\u2019attivit\u00e0 bancaria; ha fatto notare che dal 1992 gli ambienti del business russo hanno adottato una serie di documenti riguardanti l\u2019etica dell\u2019attivit\u00e0 finanziaria e imprenditoriale. Egli ha inoltre rilevato che le attivit\u00e0 di beneficenza possono essere intraprese, da imprese e singoli,\u00a0 solo su libera scelta e volontariamente, senza alcuna pressione da parte della autorit\u00e0; in questo senso, il ruolo della Chiesa, che incita e fa appello alla coscienza di tutti, senza vincolare, \u00e8 positivo.<\/p>\n<p>Nel suo intervento, l\u2019igumeno Philipp Rjabych, vicepresidente del Dipartimento per le relazioni esterne del Patriarcato di Mosca, ha affermato che la moralit\u00e0 non \u00e8 un lusso, ma un elemento indispensabile per il successo dell\u2019attivit\u00e0 economica a lunga durata. Egli ha poi illustrato le particolarit\u00e0 del rapporto col denaro e la ricchezza da parte della coscienza popolare russa ortodossa. Ha identificato le origini di tale rapporto conflittuale nella contrapposizione avvenuta in seno alla Chiesa Russa nel XVI secolo tra i seguaci del monaco Nil Sorskij e quelli del monaco Josif Volokolamskij: i primi seguivano una via di totale povert\u00e0, rifiutando ogni forma di possesso, mentre i secondi ritenevano che i beni materiali potessero essere utilizzati per servire il prossimo. Egli ha sottolineato che la Chiesa ha canonizzato entrambi i monaci, ritenendo entrambi gli insegnamenti spirituali consoni alla tradizione ortodossa.<\/p>\n<p>Il primo segretario del Consiglio di esperti \u201cEconomia e etica\u201d presso il Patriarca di Mosca e tutte le Russie P. Shashkin ha detto che occorre elaborare un modello di economia regolata da valori morali, che concili in s\u00e9 tradizione e innovazione, efficacia e giustizia, benessere materiale dei singoli e responsabilit\u00e0 sociale. Occorre inoltre passare dalle formulazioni teoretiche all\u2019applicazione pratica dei principi etici nel mondo finanziario, anche con la ricreazione di strumenti finanziari tradizionalmente cristiani, come gli istituti di credito e le finanziarie, di cui la Russia in questo momento ha grande necessit\u00e0.<\/p>\n<p>Il presidente del Consiglio direttivo della Banca Intesa A, Falico ha detto che le cause del crack economico sono da ricercarsi nella crisi della basi morali dell\u2019economia capitalistica; occorre pertanto riconsiderarne gli scopi e i fini, far coincidere l\u2019equa redistribuzione dei beni coi principi della carit\u00e0 e della solidariet\u00e0 sociale. Riferendosi all\u2019enciclica \u201cCaritas in veritate\u201d di Benedetto XVI, A. Falico ha sostenuto che nel mondo dell\u2019economia occorre una \u201crivoluzione culturale e etica\u201d, cui devono tendere tutti i cristiani.<\/p>\n<p>Tirando le somme del simposi, il card. Paul Poupard ha messo in risalto il fatto che italiani e russi hanno la stessa coscienza del legame indissolubile tra etica e economia.<\/p>","protected":false},"excerpt":{"rendered":"<p>Il 12 ottobre 2010 si \u00e8 svolto a Mosca, nei locali dell\u2019albergo \u201cDanilovskaja\u201d della Chiesa Ortodossa Russa, il simposio \u201cGli aspetti etici dell\u2019attivit\u00e0 bancaria e il ruolo sociale delle banche: le esperienze della Russia e dell\u2019Italia\u201d.<\/p>\n","protected":false},"author":2,"featured_media":27931,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10,1],"tags":[],"_links":{"self":[{"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/posts\/27883"}],"collection":[{"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/comments?post=27883"}],"version-history":[{"count":0,"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/posts\/27883\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/media\/27931"}],"wp:attachment":[{"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/media?parent=27883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/categories?post=27883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/old.mospat.ru\/it\/wp-json\/wp\/v2\/tags?post=27883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}