{"id":4274,"date":"2009-08-04T22:00:34","date_gmt":"2009-08-04T22:00:34","guid":{"rendered":"http:\/\/www.mospat.ru\/ru\/2009\/08\/04\/news4274\/"},"modified":"2009-09-30T16:38:35","modified_gmt":"2009-09-30T14:38:35","slug":"vsenoshhnoe-bdenie-v-uspenskojj-pochaevskojj-lavre-vozglavil-svyatejjshijj-patriarkh-moskovskijj-i-vseya-rusi-kirill","status":"publish","type":"post","link":"https:\/\/old.mospat.ru\/es\/2009\/08\/04\/news4274\/","title":{"rendered":"(Russian) \u0412\u0441\u0435\u043d\u043e\u0449\u043d\u043e\u0435 \u0431\u0434\u0435\u043d\u0438\u0435 \u0432 \u0423\u0441\u043f\u0435\u043d\u0441\u043a\u043e\u0439 \u041f\u043e\u0447\u0430\u0435\u0432\u0441\u043a\u043e\u0439 \u041b\u0430\u0432\u0440\u0435 \u0432\u043e\u0437\u0433\u043b\u0430\u0432\u0438\u043b \u0421\u0432\u044f\u0442\u0435\u0439\u0448\u0438\u0439 \u041f\u0430\u0442\u0440\u0438\u0430\u0440\u0445 \u041c\u043e\u0441\u043a\u043e\u0432\u0441\u043a\u0438\u0439 \u0438 \u0432\u0441\u0435\u044f \u0420\u0443\u0441\u0438 \u041a\u0438\u0440\u0438\u043b\u043b"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-es\">Perdone, este documento es accesible s\u00f3lo en idioma <a href=\"https:\/\/old.mospat.ru\/ru\/wp-json\/wp\/v2\/posts\/4274\" class=\"qtranxs-available-language-link qtranxs-available-language-link-ru\" title=\"Russian\">Ruso<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Perdone, este documento es accesible s\u00f3lo en idioma Ruso<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,11],"tags":[],"_links":{"self":[{"href":"https:\/\/old.mospat.ru\/es\/wp-json\/wp\/v2\/posts\/4274"}],"collection":[{"href":"https:\/\/old.mospat.ru\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/old.mospat.ru\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/old.mospat.ru\/es\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/old.mospat.ru\/es\/wp-json\/wp\/v2\/comments?post=4274"}],"version-history":[{"count":0,"href":"https:\/\/old.mospat.ru\/es\/wp-json\/wp\/v2\/posts\/4274\/revisions"}],"wp:attachment":[{"href":"https:\/\/old.mospat.ru\/es\/wp-json\/wp\/v2\/media?parent=4274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/old.mospat.ru\/es\/wp-json\/wp\/v2\/categories?post=4274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/old.mospat.ru\/es\/wp-json\/wp\/v2\/tags?post=4274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}